{"id":68,"date":"2022-12-29T09:34:08","date_gmt":"2022-12-29T09:34:08","guid":{"rendered":"https:\/\/themepanthers.com\/wp\/vankine\/v1\/?page_id=68"},"modified":"2026-05-29T13:48:19","modified_gmt":"2026-05-29T13:48:19","slug":"contactanos","status":"publish","type":"page","link":"https:\/\/www.segurossuarez.com\/en\/contactanos\/","title":{"rendered":"Contactanos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"68\" class=\"elementor elementor-68\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae0d017 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"ae0d017\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0775bfa\" data-id=\"0775bfa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b418323 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"b418323\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"650\" height=\"494\" src=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Ambato-1.jpg\" class=\"elementor-animation-bounce-in attachment-full size-full wp-image-4811\" alt=\"\" srcset=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Ambato-1.jpg 650w, https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Ambato-1-300x228.jpg 300w, https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Ambato-1-600x456.jpg 600w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Matriz Ambato<\/h3><p class=\"elementor-image-box-description\">Calle Rodrigo Pachano y Montalvo. <br>\nPlanta Baja. Edificio Doctor Calero.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6f0985d\" data-id=\"6f0985d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a1412a elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"2a1412a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"650\" height=\"494\" src=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Quito.jpg\" class=\"elementor-animation-bounce-in attachment-full size-full wp-image-4814\" alt=\"\" srcset=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Quito.jpg 650w, https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Quito-300x228.jpg 300w, https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Quito-600x456.jpg 600w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Agencia Quito<\/h3><p class=\"elementor-image-box-description\">Av. 6 de Diciembre y Checoslovaquia. <br>Edificio Seis. 2do Piso. Oficina 2 Y 3<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e00dc29\" data-id=\"e00dc29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9e99a9 elementor-position-top elementor-invisible elementor-widget elementor-widget-image-box\" data-id=\"c9e99a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInUp&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"650\" height=\"494\" src=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Cuenca.jpg\" class=\"elementor-animation-bounce-in attachment-full size-full wp-image-4813\" alt=\"\" srcset=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Cuenca.jpg 650w, https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Cuenca-300x228.jpg 300w, https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Cuenca-600x456.jpg 600w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Agencia Cuenca<\/h3><p class=\"elementor-image-box-description\">Calle Gran Colombia 21-251 y Av. Unidad Nacional. Edificio Mirador del R\u00edo - PB.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc90c81 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"dc90c81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6dd3d99\" data-id=\"6dd3d99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1185798 elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"1185798\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/themepanthers.com\/wp\/vankine\/v1\/wp-content\/uploads\/2023\/01\/cont-1.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                         \r\n            <div class=\"contact-infor\">\r\n                \r\n                <h6 class=\"title_no_a_24\">   Punto de Atenci\u00f3n Riobamba<\/h6>\r\n                                        <span>Tel\u00e9fono: 0990353885<\/span>\r\n                    <\/div>\r\n                                        <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4eecfbb\" data-id=\"4eecfbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b86c9e1 elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"b86c9e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/themepanthers.com\/wp\/vankine\/v1\/wp-content\/uploads\/2023\/01\/cont-1.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                         \r\n            <div class=\"contact-infor\">\r\n                \r\n                <h6 class=\"title_no_a_24\">   Punto de Atenci\u00f3n Portoviejo<\/h6>\r\n                                        <span>Tel\u00e9fono: 0990454477<\/span>\r\n                    <\/div>\r\n                                        <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cf1d738\" data-id=\"cf1d738\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d786a22 elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"d786a22\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/themepanthers.com\/wp\/vankine\/v1\/wp-content\/uploads\/2023\/01\/cont-1.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                         \r\n            <div class=\"contact-infor\">\r\n                \r\n                <h6 class=\"title_no_a_24\">   Punto de Atenci\u00f3n Machala<\/h6>\r\n                                        <span>Tel\u00e9fono: 0981981458<\/span>\r\n                    <\/div>\r\n                                        <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb53fad elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"fb53fad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1481d47\" data-id=\"1481d47\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9042baf elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"9042baf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/themepanthers.com\/wp\/vankine\/v1\/wp-content\/uploads\/2023\/01\/cont-1.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                         \r\n            <div class=\"contact-infor\">\r\n                \r\n                <h6 class=\"title_no_a_24\">   Punto de Atenci\u00f3n Salcedo<\/h6>\r\n                                        <span>Tel\u00e9fono: 0997303921<\/span>\r\n                    <\/div>\r\n                                        <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ac7d7e5\" data-id=\"ac7d7e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5441e2d elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"5441e2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/themepanthers.com\/wp\/vankine\/v1\/wp-content\/uploads\/2023\/01\/cont-1.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                         \r\n            <div class=\"contact-infor\">\r\n                \r\n                <h6 class=\"title_no_a_24\">   Punto de Atenci\u00f3n Tulc\u00e1n<\/h6>\r\n                                        <span>Tel\u00e9fono: 0997722410<\/span>\r\n                    <\/div>\r\n                                        <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-886d497\" data-id=\"886d497\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a95534 elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"9a95534\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/themepanthers.com\/wp\/vankine\/v1\/wp-content\/uploads\/2023\/01\/cont-1.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                         \r\n            <div class=\"contact-infor\">\r\n                \r\n                <h6 class=\"title_no_a_24\">   Punto de Atenci\u00f3n Santa Ana<\/h6>\r\n                                        <span>Tel\u00e9fono: 0997752700<\/span>\r\n                    <\/div>\r\n                                        <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a564f2c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a564f2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-10adcf0\" data-id=\"10adcf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f53fca3 elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"f53fca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/themepanthers.com\/wp\/vankine\/v1\/wp-content\/uploads\/2023\/01\/cont-1.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                         \r\n            <div class=\"contact-infor\">\r\n                \r\n                <h6 class=\"title_no_a_24\">   Punto de Atenci\u00f3n San Jos\u00e9 de Chimbo<\/h6>\r\n                                        <span>Tel\u00e9fono: 0991323629<\/span>\r\n                    <\/div>\r\n                                        <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-fb8c74b\" data-id=\"fb8c74b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9d1c25c\" data-id=\"9d1c25c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-536b1b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"536b1b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f68a3a4\" data-id=\"f68a3a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d49dd66 elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"d49dd66\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/themepanthers.com\/wp\/vankine\/v1\/wp-content\/uploads\/2023\/01\/cont-2.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                                        <div class=\"contact-infor\">\r\n                   \r\n                <h6 class=\"title_no_a_24\">Email<\/h6>\r\n            \r\n                                            <a href=\"mailto:info@segurossuarez.com\n\">info@segurossuarez.com\n<\/a>\r\n                                <\/div>\r\n                        <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0ac9c80\" data-id=\"0ac9c80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a34cd0 elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"7a34cd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/themepanthers.com\/wp\/vankine\/v1\/wp-content\/uploads\/2023\/01\/cont-3.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                                <div class=\"contact-infor\">\r\n                          \r\n                <h6 class=\"title_no_a_24\">Ll\u00e1manos<\/h6>\r\n                                        <a href=\"tel:(03) 3920141\n\">(03) 3920141\n<\/a>\r\n                                <\/div>\r\n                                <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7664a29\" data-id=\"7664a29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e775be elementor-invisible elementor-widget elementor-widget-vankine-contact-box-v1\" data-id=\"7e775be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-contact-box-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t \r\n \r\n    <div class=\"contact_box_content\">\r\n                                                        <div class=\"icon trans\">\r\n                        <img decoding=\"async\" src=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Icono-Horario.png\" alt=\"img\" \/>\r\n                    <\/div>\r\n                                                                                <div class=\"contact-infor\">\r\n                        <h6 class=\"title_no_a_24\">Horario<\/h6>\r\n                                        <span>Matriz Lun - Vie: 08h30 a 18h00<\/span>\r\n                    <\/div>\r\n                <\/div>\r\n \r\n  \r\n  \r\n\r\n  \r\n \r\n\r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b50e792 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"b50e792\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f1547c2\" data-id=\"f1547c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77f11a6 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"77f11a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"914\" height=\"690\" src=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/04\/Chica-Call-Center.png\" class=\"attachment-large size-large wp-image-4120\" alt=\"\" srcset=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/04\/Chica-Call-Center.png 914w, https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/04\/Chica-Call-Center-300x226.png 300w, https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/04\/Chica-Call-Center-768x580.png 768w, https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/04\/Chica-Call-Center-600x453.png 600w\" sizes=\"(max-width: 914px) 100vw, 914px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-aff2c45 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"aff2c45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7c83f14\" data-id=\"7c83f14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18c2af9 elementor-invisible elementor-widget elementor-widget-vankine-title-v1\" data-id=\"18c2af9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-title-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"section_title type_one\">\r\n                            <h6 class=\"sm_title\"> CALL CENTER<\/h6>\r\n                                        <div class=\"title_whole\"> \r\n                        <h2 class=\"title\"> Ahora puedes reportar tus siniestros a trav\u00e9s de nuestro Call Center  <\/h2>\r\n                <\/div>\r\n                                <\/div>\r\n            \r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d3ecd9 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"4d3ecd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"tel:033920141\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-alt\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18fd0d3 elementor-invisible elementor-widget elementor-widget-vankine-title-v1\" data-id=\"18fd0d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"vankine-title-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"section_title type_one\">\r\n                            <h6 class=\"sm_title\"> Ll\u00e1manos<\/h6>\r\n                                        <div class=\"title_whole\"> \r\n                        <h2 class=\"title\"> (03) 3920141  <\/h2>\r\n                <\/div>\r\n                                        <p> \u00a1Perm\u00edtenos ayudarte de una manera r\u00e1pida y eficaz!<\/p>\r\n                    <\/div>\r\n            \r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a465840 elementor-widget elementor-widget-spacer\" data-id=\"a465840\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c23f3d5 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"c23f3d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-927a4fa elementor-section-full_width elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"927a4fa\" data-element_type=\"section\" data-e-type=\"section\" id=\"ubicanos\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5de05cc\" data-id=\"5de05cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49ac0c5 elementor-widget elementor-widget-google_maps\" data-id=\"49ac0c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=seguros%20suarez%20ambato&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"seguros suarez ambato\"\n\t\t\t\t\taria-label=\"seguros suarez ambato\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8e90f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"a8e90f9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c76861d\" data-id=\"c76861d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4380665 elementor-widget elementor-widget-vankine-title-v1\" data-id=\"4380665\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"vankine-title-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                    <div class=\"section_title type_one\">\r\n                            <h6 class=\"sm_title\"> Escr\u00edbenos<\/h6>\r\n                                        <div class=\"title_whole\"> \r\n                        <h2 class=\"title\"> Estamos listos para asesorarte  <\/h2>\r\n                <\/div>\r\n                                        <p> Si tienes alguna duda, comentario o requerimiento, no dudes en escribirnos, y uno de nuestros asesores te contestar\u00e1 en el menor tiempo posible.<\/p>\r\n                    <\/div>\r\n            \r\n\r\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06bfb90 elementor-widget elementor-widget-vankine-social-media-v1\" data-id=\"06bfb90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"vankine-social-media-v1.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div class=\"social-icons\">\r\n                       \r\n<ul>\r\n                    <li><a href=\"https:\/\/www.facebook.com\/segurossuarez.ec\"  class=\"m_icon\"   > <i class=\"fab fa-facebook\"><\/i>\r\n              \r\n            <\/a><\/li>\r\n                    <li><a href=\"https:\/\/twitter.com\/segurossuarez\"  class=\"m_icon\"   > <i class=\"fab fa-twitter\"><\/i>\r\n              \r\n            <\/a><\/li>\r\n                    <li><a href=\"https:\/\/www.instagram.com\/segurossuarez\/\"  class=\"m_icon\"   > <i class=\"fab fa-instagram\"><\/i>\r\n              \r\n            <\/a><\/li>\r\n                    <li><a href=\"https:\/\/www.linkedin.com\/company\/24775276\/admin\/\"  class=\"m_icon\"   > <i class=\"fa-brands fa-linkedin\"><\/i>\r\n              \r\n            <\/a><\/li>\r\n                <\/ul>\r\n<\/div>\r\n \r\n\t\r\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9caf95\" data-id=\"e9caf95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f475afc elementor-widget elementor-widget-text-editor\" data-id=\"f475afc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f6792-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"6792\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/68#wpcf7-f6792-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"6792\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f6792-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:6792,&quot;conditions&quot;:[{&quot;then_field&quot;:&quot;group-vehicular&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;team_safe_type_name&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;Seguro Vehicular&quot;}]},{&quot;then_field&quot;:&quot;group-Medic&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;team_safe_type_name&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;Seguro M\\u00e9dico&quot;}]},{&quot;then_field&quot;:&quot;group-Jubilacion&quot;,&quot;and_rules&quot;:[{&quot;if_field&quot;:&quot;team_safe_type_name&quot;,&quot;operator&quot;:&quot;equals&quot;,&quot;if_value&quot;:&quot;Vida Jubilaci\\u00f3n&quot;}]}],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;notice_dismissed_rollback-cf7-6.0.1&quot;:true}}\" \/>\n<\/fieldset>\n<p><label> Nombre<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Nombre\" \/><\/span> <\/label>\n<\/p>\n<p><label> Cedula Identidad<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Cedula\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"vat\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Cedula\" \/><\/span> <\/label>\n<\/p>\n<p><label> Ciudad<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"city\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"city\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"city\" \/><\/span> <\/label>\n<\/p>\n<p><label> Correo Electr\u00f3nico<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email_from\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email_from\" \/><\/span> <\/label>\n<\/p>\n<p><label> Celular<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Celular\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Celular\" \/><\/span> <\/label>\n<\/p>\n<p><label>Selecciona un tipo de seguro<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"team_safe_type_name\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"team_safe_type_name\"><option value=\"\"><\/option><option value=\"Seguro Vehicular\">Seguro Vehicular<\/option><option value=\"Seguro M\u00e9dico\">Seguro M\u00e9dico<\/option><option value=\"Vida Jubilaci\u00f3n\">Vida Jubilaci\u00f3n<\/option><\/select><\/span><br \/>\n<\/label>\n<\/p>\n<p><label>Medio de contacto<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"contact_medium\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"contact_medium\"><option value=\"\"><\/option><option value=\"Llamada\">Llamada<\/option><option value=\"WhatsApp\">WhatsApp<\/option><option value=\"Email\">Email<\/option><\/select><\/span><br \/>\n<\/label>\n<\/p>\n<p><label>Horario de contacto<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"contact_time\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"contact_time\"><option value=\"\"><\/option><option value=\"08:30 - 10:30\">08:30 &#8211; 10:30<\/option><option value=\"10:30 - 12:30\">10:30 &#8211; 12:30<\/option><option value=\"12:30 - 14:30\">12:30 &#8211; 14:30<\/option><option value=\"14:30 - 16:30\">14:30 &#8211; 16:30<\/option><option value=\"16:30 - 18:30\">16:30 &#8211; 18:30<\/option><\/select><\/span><br \/>\n<\/label>\n<\/p>\n<div data-id=\"group-Medic\" data-orig_data_id=\"group-Medic\"  data-class=\"wpcf7cf_group\">\n\t<p><label> \u00bfPara qui\u00e9n es el seguro?<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"safe_recipient\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"safe_recipient\"><option value=\"\"><\/option><option value=\"Para M\u00ed\">Para M\u00ed<\/option><option value=\"Para mi grupo familiar\">Para mi grupo familiar<\/option><\/select><\/span><br \/>\n<\/label>\n\t<\/p>\n\t<p><label> Genero<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"gender_medic\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"gender_medic\"><option value=\"\"><\/option><option value=\"Masculino\">Masculino<\/option><option value=\"Femenino\">Femenino<\/option><option value=\"Otro\">Otro<\/option><\/select><\/span><br \/>\n<\/label>\n\t<\/p>\n\t<p><label> Fecha de nacimiento<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"birth_date_medic\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"birth_date_medic\" \/><\/span> <\/label>\n\t<\/p>\n<\/div>\n<div data-id=\"group-vehicular\" data-orig_data_id=\"group-vehicular\"  data-class=\"wpcf7cf_group\">\n\t<p><label> Marca<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"mark\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"mark\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"mark\" \/><\/span><br \/>\n<\/label>\n\t<\/p>\n\t<p><label> Modelo<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"model\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"model\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"model\" \/><\/span><br \/>\n<\/label>\n\t<\/p>\n\t<p><label> Placa<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"plate\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"plate\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"plate\" \/><\/span><br \/>\n<\/label>\n\t<\/p>\n\t<p><label> A\u00f1o<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-year\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"year\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-year\" \/><\/span><br \/>\n<\/label>\n\t<\/p>\n\t<p><label> Tipo<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"type_vehicle\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"type_vehicle\"><option value=\"\"><\/option><option value=\"Pesados\">Pesados<\/option><option value=\"Livianos\">Livianos<\/option><option value=\"Motos\">Motos<\/option><\/select><\/span><br \/>\n<\/label>\n\t<\/p>\n<\/div>\n<div data-id=\"group-Jubilacion\" data-orig_data_id=\"group-Jubilacion\"  data-class=\"wpcf7cf_group\">\n\t<p><label> Genero<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"gender_jub\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"gender_jub\"><option value=\"\"><\/option><option value=\"Masculino\">Masculino<\/option><option value=\"Femenino\">Femenino<\/option><option value=\"Otro\">Otro<\/option><\/select><\/span><br \/>\n<\/label>\n\t<\/p>\n\t<p><label> Fecha de nacimiento<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"birth_date_jub\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"birth_date_jub\" \/><\/span> <\/label>\n\t<\/p>\n<\/div>\n<p><label> Tu mensaje (opcional)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"Mensaje\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"description\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"Mensaje\" \/><\/span> <\/label>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"term_and_conditions\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"term_and_conditions\" value=\"1\" class=\"required\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acepto la <a href=\"https:\/\/www.segurossuarez.com\/politica-de-privacidad\">Pol\u00edtica de Privacidad<\/a>.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Matriz Ambato Calle Rodrigo Pachano y Montalvo. Planta Baja. Edificio Doctor Calero. Agencia Quito Av. 6 de Diciembre y Checoslovaquia. Edificio Seis. 2do Piso. Oficina 2 Y 3 Agencia Cuenca Calle Gran Colombia 21-251 y Av. Unidad Nacional. Edificio Mirador del R\u00edo &#8211; PB. Punto de Atenci\u00f3n Riobamba Tel\u00e9fono: 0990353885 Punto de Atenci\u00f3n Portoviejo Tel\u00e9fono: 0990454477 Punto de Atenci\u00f3n Machala Tel\u00e9fono: 0981981458 Punto de Atenci\u00f3n Salcedo Tel\u00e9fono: 0997303921 Punto de Atenci\u00f3n Tulc\u00e1n Tel\u00e9fono: 0997722410 Punto de Atenci\u00f3n Santa Ana Tel\u00e9fono: 0997752700 Punto de Atenci\u00f3n San Jos\u00e9 de Chimbo Tel\u00e9fono: 0991323629 Email info@segurossuarez.com Ll\u00e1manos (03) 3920141 Horario Matriz Lun &#8211; Vie: 08h30 a 18h00 CALL CENTER Ahora puedes reportar tus siniestros a trav\u00e9s de nuestro Call Center Ll\u00e1manos (03) 3920141 \u00a1Perm\u00edtenos ayudarte de una manera r\u00e1pida y eficaz! Escr\u00edbenos Estamos listos para asesorarte Si tienes alguna duda, comentario o requerimiento, no dudes en escribirnos, y uno de nuestros asesores te contestar\u00e1 en el menor tiempo posible.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-68","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contactanos - Seguros Suarez<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.segurossuarez.com\/en\/contactanos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contactanos - Seguros Suarez\" \/>\n<meta property=\"og:description\" content=\"Matriz Ambato Calle Rodrigo Pachano y Montalvo. Planta Baja. Edificio Doctor Calero. Agencia Quito Av. 6 de Diciembre y Checoslovaquia. Edificio Seis. 2do Piso. Oficina 2 Y 3 Agencia Cuenca Calle Gran Colombia 21-251 y Av. Unidad Nacional. Edificio Mirador del R\u00edo &#8211; PB. Punto de Atenci\u00f3n Riobamba Tel\u00e9fono: 0990353885 Punto de Atenci\u00f3n Portoviejo Tel\u00e9fono: 0990454477 Punto de Atenci\u00f3n Machala Tel\u00e9fono: 0981981458 Punto de Atenci\u00f3n Salcedo Tel\u00e9fono: 0997303921 Punto de Atenci\u00f3n Tulc\u00e1n Tel\u00e9fono: 0997722410 Punto de Atenci\u00f3n Santa Ana Tel\u00e9fono: 0997752700 Punto de Atenci\u00f3n San Jos\u00e9 de Chimbo Tel\u00e9fono: 0991323629 Email info@segurossuarez.com Ll\u00e1manos (03) 3920141 Horario Matriz Lun &#8211; Vie: 08h30 a 18h00 CALL CENTER Ahora puedes reportar tus siniestros a trav\u00e9s de nuestro Call Center Ll\u00e1manos (03) 3920141 \u00a1Perm\u00edtenos ayudarte de una manera r\u00e1pida y eficaz! Escr\u00edbenos Estamos listos para asesorarte Si tienes alguna duda, comentario o requerimiento, no dudes en escribirnos, y uno de nuestros asesores te contestar\u00e1 en el menor tiempo posible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.segurossuarez.com\/en\/contactanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Seguros Suarez\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/segurossuarez.ec\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T13:48:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Ambato-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"494\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@segurossuarez\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/contactanos\\\/\",\"url\":\"https:\\\/\\\/www.segurossuarez.com\\\/contactanos\\\/\",\"name\":\"Contactanos - Seguros Suarez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/contactanos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/contactanos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.segurossuarez.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Direccion-Ambato-1.jpg\",\"datePublished\":\"2022-12-29T09:34:08+00:00\",\"dateModified\":\"2026-05-29T13:48:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/contactanos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.segurossuarez.com\\\/contactanos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/contactanos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.segurossuarez.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Direccion-Ambato-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.segurossuarez.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Direccion-Ambato-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/contactanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.segurossuarez.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contactanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/#website\",\"url\":\"https:\\\/\\\/www.segurossuarez.com\\\/\",\"name\":\"Seguros Su\u00e1rez\",\"description\":\"Aseguramos tu bienestar\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/#organization\"},\"alternateName\":\"Seguros Su\u00e1rez\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.segurossuarez.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/#organization\",\"name\":\"Seguros Su\u00e1rez\",\"alternateName\":\"Seguros Su\u00e1rez\",\"url\":\"https:\\\/\\\/www.segurossuarez.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.segurossuarez.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Nuevo-Logo-Blanco-Yoast.png\",\"contentUrl\":\"https:\\\/\\\/www.segurossuarez.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Nuevo-Logo-Blanco-Yoast.png\",\"width\":2000,\"height\":2000,\"caption\":\"Seguros Su\u00e1rez\"},\"image\":{\"@id\":\"https:\\\/\\\/www.segurossuarez.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/segurossuarez.ec\",\"https:\\\/\\\/x.com\\\/segurossuarez\",\"https:\\\/\\\/www.instagram.com\\\/segurossuarez\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/segurossuarez\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contactanos - Seguros Suarez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.segurossuarez.com\/en\/contactanos\/","og_locale":"en_US","og_type":"article","og_title":"Contactanos - Seguros Suarez","og_description":"Matriz Ambato Calle Rodrigo Pachano y Montalvo. Planta Baja. Edificio Doctor Calero. Agencia Quito Av. 6 de Diciembre y Checoslovaquia. Edificio Seis. 2do Piso. Oficina 2 Y 3 Agencia Cuenca Calle Gran Colombia 21-251 y Av. Unidad Nacional. Edificio Mirador del R\u00edo &#8211; PB. Punto de Atenci\u00f3n Riobamba Tel\u00e9fono: 0990353885 Punto de Atenci\u00f3n Portoviejo Tel\u00e9fono: 0990454477 Punto de Atenci\u00f3n Machala Tel\u00e9fono: 0981981458 Punto de Atenci\u00f3n Salcedo Tel\u00e9fono: 0997303921 Punto de Atenci\u00f3n Tulc\u00e1n Tel\u00e9fono: 0997722410 Punto de Atenci\u00f3n Santa Ana Tel\u00e9fono: 0997752700 Punto de Atenci\u00f3n San Jos\u00e9 de Chimbo Tel\u00e9fono: 0991323629 Email info@segurossuarez.com Ll\u00e1manos (03) 3920141 Horario Matriz Lun &#8211; Vie: 08h30 a 18h00 CALL CENTER Ahora puedes reportar tus siniestros a trav\u00e9s de nuestro Call Center Ll\u00e1manos (03) 3920141 \u00a1Perm\u00edtenos ayudarte de una manera r\u00e1pida y eficaz! Escr\u00edbenos Estamos listos para asesorarte Si tienes alguna duda, comentario o requerimiento, no dudes en escribirnos, y uno de nuestros asesores te contestar\u00e1 en el menor tiempo posible.","og_url":"https:\/\/www.segurossuarez.com\/en\/contactanos\/","og_site_name":"Seguros Suarez","article_publisher":"https:\/\/www.facebook.com\/segurossuarez.ec","article_modified_time":"2026-05-29T13:48:19+00:00","og_image":[{"width":650,"height":494,"url":"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Ambato-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@segurossuarez","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.segurossuarez.com\/contactanos\/","url":"https:\/\/www.segurossuarez.com\/contactanos\/","name":"Contactanos - Seguros Suarez","isPartOf":{"@id":"https:\/\/www.segurossuarez.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.segurossuarez.com\/contactanos\/#primaryimage"},"image":{"@id":"https:\/\/www.segurossuarez.com\/contactanos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Ambato-1.jpg","datePublished":"2022-12-29T09:34:08+00:00","dateModified":"2026-05-29T13:48:19+00:00","breadcrumb":{"@id":"https:\/\/www.segurossuarez.com\/contactanos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.segurossuarez.com\/contactanos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.segurossuarez.com\/contactanos\/#primaryimage","url":"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Ambato-1.jpg","contentUrl":"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2023\/05\/Direccion-Ambato-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.segurossuarez.com\/contactanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.segurossuarez.com\/"},{"@type":"ListItem","position":2,"name":"Contactanos"}]},{"@type":"WebSite","@id":"https:\/\/www.segurossuarez.com\/#website","url":"https:\/\/www.segurossuarez.com\/","name":"Seguros Su\u00e1rez","description":"Aseguramos tu bienestar","publisher":{"@id":"https:\/\/www.segurossuarez.com\/#organization"},"alternateName":"Seguros Su\u00e1rez","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.segurossuarez.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.segurossuarez.com\/#organization","name":"Seguros Su\u00e1rez","alternateName":"Seguros Su\u00e1rez","url":"https:\/\/www.segurossuarez.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.segurossuarez.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2024\/03\/Nuevo-Logo-Blanco-Yoast.png","contentUrl":"https:\/\/www.segurossuarez.com\/wp-content\/uploads\/2024\/03\/Nuevo-Logo-Blanco-Yoast.png","width":2000,"height":2000,"caption":"Seguros Su\u00e1rez"},"image":{"@id":"https:\/\/www.segurossuarez.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/segurossuarez.ec","https:\/\/x.com\/segurossuarez","https:\/\/www.instagram.com\/segurossuarez","https:\/\/www.linkedin.com\/company\/segurossuarez"]}]}},"_links":{"self":[{"href":"https:\/\/www.segurossuarez.com\/en\/wp-json\/wp\/v2\/pages\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.segurossuarez.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.segurossuarez.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.segurossuarez.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.segurossuarez.com\/en\/wp-json\/wp\/v2\/comments?post=68"}],"version-history":[{"count":41,"href":"https:\/\/www.segurossuarez.com\/en\/wp-json\/wp\/v2\/pages\/68\/revisions"}],"predecessor-version":[{"id":8417,"href":"https:\/\/www.segurossuarez.com\/en\/wp-json\/wp\/v2\/pages\/68\/revisions\/8417"}],"wp:attachment":[{"href":"https:\/\/www.segurossuarez.com\/en\/wp-json\/wp\/v2\/media?parent=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}